 {"id":7708,"date":"2023-04-10T19:06:41","date_gmt":"2023-04-10T12:06:41","guid":{"rendered":"https:\/\/drjill.co.th\/home\/?page_id=7708"},"modified":"2023-07-26T12:52:31","modified_gmt":"2023-07-26T05:52:31","slug":"eye-cream","status":"publish","type":"page","link":"https:\/\/drjill.co.th\/home\/eye-cream\/","title":{"rendered":"Eye Cream"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7708\" class=\"elementor elementor-7708\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e5c580 elementor-section-full_width elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"9e5c580\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97cc709\" data-id=\"97cc709\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc96422 elementor-widget elementor-widget-video\" data-id=\"fc96422\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;start&quot;:0,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/drjill.co.th\/home\/files-drjl\/video\/Banner_eyecream-v1.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f040cc3 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"f040cc3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f5c012\" data-id=\"6f5c012\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1f0bc5 elementor-widget elementor-widget-mkdf_section_title\" data-id=\"f1f0bc5\" data-element_type=\"widget\" data-widget_type=\"mkdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-section-title-holder  mkdf-st-top-tagline-position mkdf-st-center-position  \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t\t\t<span class=\"mkdf-st-tagline\" style=\"color: #1273B8\">\n\t\t\t\tEye Cream\t\t\t<\/span>\n\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\t\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32\t\t\t<\/h2>\n\t\t\t\t\t\t\t<h5 class=\"mkdf-st-subtitle\" >\n\t\t\t\t\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1c\u0e34\u0e27\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d4ede4 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"3d4ede4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2496044\" data-id=\"2496044\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b57616a elementor-widget elementor-widget-text-editor\" data-id=\"b57616a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b><span style=\"font-size: x-large;\">\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23<\/span>\n<span style=\"font-size: x-large;\"><span style=\"color: #1273b8;\">4<\/span> \u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e2a\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07<\/span>\n<\/b><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c45b6c1 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"c45b6c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f4deaae\" data-id=\"f4deaae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd8aae7 elementor-widget elementor-widget-image\" data-id=\"bd8aae7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04.png\" class=\"elementor-animation-bob attachment-large size-large wp-image-7974\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04.png 500w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04-300x300.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04-150x150.png 150w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91c854c elementor-widget elementor-widget-text-editor\" data-id=\"91c854c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Palmitoyl<br \/>Pentapeptide &#8211; 4<\/strong><br \/>\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e25\u0e25\u0e32\u0e40\u0e08\u0e19<br \/>\u0e25\u0e14\u0e23\u0e2d\u0e22\u0e04\u0e25\u0e49\u0e33\u0e43\u0e15\u0e49\u0e15\u0e32<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-69c87f6\" data-id=\"69c87f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-568ea1b elementor-widget elementor-widget-image\" data-id=\"568ea1b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04.png\" class=\"elementor-animation-bob attachment-large size-large wp-image-7975\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04.png 500w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04-300x300.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04-150x150.png 150w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf5d373 elementor-widget elementor-widget-text-editor\" data-id=\"bf5d373\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Acetyl<br \/>Tetrapeptide &#8211; 5<\/strong><br \/>\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e14<br \/>\u0e43\u0e15\u0e49\u0e15\u0e32\u0e04\u0e25\u0e49\u0e33\u0e08\u0e32\u0e07\u0e25\u0e07<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d6d58ac\" data-id=\"d6d58ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-388f02c elementor-widget elementor-widget-image\" data-id=\"388f02c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04.png\" class=\"elementor-animation-bob attachment-large size-large wp-image-7976\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04.png 500w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04-300x300.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04-150x150.png 150w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e77c18 elementor-widget elementor-widget-text-editor\" data-id=\"4e77c18\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Acetyl<br \/>Hexapeptide &#8211; 8<\/strong><br \/>\u0e01\u0e25\u0e44\u0e01\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e09\u0e35\u0e14\u0e42\u0e1a\u0e17\u0e47\u0e2d\u0e01\u0e0a\u0e4c<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0a74839\" data-id=\"0a74839\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92ac9ea elementor-widget elementor-widget-image\" data-id=\"92ac9ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04.png\" class=\"elementor-animation-bob attachment-large size-large wp-image-7977\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04.png 500w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04-300x300.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04-150x150.png 150w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bb36b2 elementor-widget elementor-widget-text-editor\" data-id=\"5bb36b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Hyaluronic<br \/>Filling Spheres\u2122<\/strong><br \/>\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e14\u0e49\u0e27\u0e22\u0e44\u0e2e\u0e22\u0e32\u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c<br \/>\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e27 1,000 \u0e40\u0e17\u0e48\u0e32*<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-60f288c elementor-widget elementor-widget-text-editor\" data-id=\"60f288c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-prompt-small\">* \u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 BASF THE CHEMICAL COMPANY<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1458b60 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"1458b60\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc948ea\" data-id=\"fc948ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7a7ac76 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"7a7ac76\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-aa7f241\" data-id=\"aa7f241\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c38551d elementor-widget elementor-widget-text-editor\" data-id=\"c38551d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b><span style=\"font-size: x-large;\">\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23 <font color=\"#1273B8\">4<\/font> \u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e2a\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07<\/span><\/b><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf2c2f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"cf2c2f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ced6233\" data-id=\"ced6233\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c94b259 elementor-widget elementor-widget-image\" data-id=\"c94b259\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04.png\" class=\"attachment-large size-large wp-image-7974\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04.png 500w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04-300x300.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04-150x150.png 150w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients01-04-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a14f174\" data-id=\"a14f174\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4414625 elementor-widget elementor-widget-text-editor\" data-id=\"4414625\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Palmitoyl Pentapeptide &#8211; 4<\/strong><br \/>\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e25\u0e25\u0e32\u0e40\u0e08\u0e19<br \/>\u0e25\u0e14\u0e23\u0e2d\u0e22\u0e04\u0e25\u0e49\u0e33\u0e43\u0e15\u0e49\u0e15\u0e32<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55ad2fb elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"55ad2fb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c90c2d4\" data-id=\"c90c2d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b6043a elementor-widget elementor-widget-image\" data-id=\"4b6043a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04.png\" class=\"attachment-large size-large wp-image-7975\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04.png 500w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04-300x300.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04-150x150.png 150w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients02-04-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-761dc5e\" data-id=\"761dc5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca4c6db elementor-widget elementor-widget-text-editor\" data-id=\"ca4c6db\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Acetyl Tetrapeptide &#8211; 5<\/strong><br \/>\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e14<br \/>\u0e43\u0e15\u0e49\u0e15\u0e32\u0e04\u0e25\u0e49\u0e33\u0e08\u0e32\u0e07\u0e25\u0e07<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-97a8ddf elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"97a8ddf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-da0308a\" data-id=\"da0308a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abc041c elementor-widget elementor-widget-image\" data-id=\"abc041c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04.png\" class=\"attachment-large size-large wp-image-7976\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04.png 500w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04-300x300.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04-150x150.png 150w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients03-04-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-68030e3\" data-id=\"68030e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c2bfe9 elementor-widget elementor-widget-text-editor\" data-id=\"1c2bfe9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Acetyl Hexapeptide &#8211; 8<\/strong><br \/>\u0e01\u0e25\u0e44\u0e01\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e09\u0e35\u0e14\u0e42\u0e1a\u0e17\u0e47\u0e2d\u0e01\u0e0a\u0e4c<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a497950 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"a497950\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-178a27f\" data-id=\"178a27f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ec1fd3 elementor-widget elementor-widget-image\" data-id=\"2ec1fd3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04.png\" class=\"attachment-large size-large wp-image-7977\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04.png 500w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04-300x300.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04-150x150.png 150w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/nutrients04-04-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-43fbb0f\" data-id=\"43fbb0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a70801 elementor-widget elementor-widget-text-editor\" data-id=\"2a70801\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Hyaluronic Filling Spheres\u2122<\/strong><br \/>\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e14\u0e49\u0e27\u0e22<br \/>\u0e44\u0e2e\u0e22\u0e32\u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c<br \/>\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e27<br \/>1,000 \u0e40\u0e17\u0e48\u0e32*<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-51f60f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"51f60f0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2319b3d\" data-id=\"2319b3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98617de elementor-widget elementor-widget-text-editor\" data-id=\"98617de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-prompt-small\">* \u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 BASF THE CHEMICAL COMPANY<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d5cea4 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"5d5cea4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c5409a\" data-id=\"9c5409a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-edfe2c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"edfe2c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-378b922\" data-id=\"378b922\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ddcd27 elementor-widget elementor-widget-mkdf_section_title\" data-id=\"1ddcd27\" data-element_type=\"widget\" data-widget_type=\"mkdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-section-title-holder  mkdf-st-top-tagline-position mkdf-st-center-position  \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t\t\t<span class=\"mkdf-st-tagline\" style=\"color: #1273B8\">\n\t\t\t\tEye Cream\t\t\t<\/span>\n\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\t\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e44\u0e21\u0e48\u0e23\u0e30\u0e04\u0e32\u0e22\u0e40\u0e04\u0e37\u0e2d\u0e07\t\t\t<\/h2>\n\t\t\t\t\t\t\t<h5 class=\"mkdf-st-subtitle\" >\n\t\t\t\t\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 Greenleaf*\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-acc3f84 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"acc3f84\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-153e7f3\" data-id=\"153e7f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-ddcc88a\" data-id=\"ddcc88a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a05ef7 elementor-widget elementor-widget-text-editor\" data-id=\"4a05ef7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-kanit17\">\u2713 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1a\u0e32\u0e07\u0e40\u0e1a\u0e32<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-0a68c45\" data-id=\"0a68c45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c3db5a elementor-widget elementor-widget-text-editor\" data-id=\"8c3db5a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-kanit17\">\u2713 \u0e0b\u0e36\u0e21\u0e0b\u0e32\u0e1a\u0e44\u0e27<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-d7d5d23\" data-id=\"d7d5d23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71ed483 elementor-widget elementor-widget-text-editor\" data-id=\"71ed483\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-kanit17\">\u2713 \u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e04\u0e23\u0e32\u0e1a<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-5d58429\" data-id=\"5d58429\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d92039 elementor-widget elementor-widget-text-editor\" data-id=\"3d92039\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-kanit17\">\u2713 \u0e44\u0e21\u0e48\u0e2b\u0e19\u0e31\u0e01\u0e2b\u0e19\u0e49\u0e32<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-dd78f6c\" data-id=\"dd78f6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ea83a07 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"ea83a07\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7f67824\" data-id=\"7f67824\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-962aa0b elementor-widget elementor-widget-text-editor\" data-id=\"962aa0b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-prompt-small\">* \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e23\u0e30\u0e04\u0e32\u0e22\u0e40\u0e04\u0e37\u0e2d\u0e07\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e31\u0e07<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f46683 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"5f46683\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbd3718\" data-id=\"dbd3718\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22e413b elementor-widget elementor-widget-mkdf_section_title\" data-id=\"22e413b\" data-element_type=\"widget\" data-widget_type=\"mkdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-section-title-holder   mkdf-st-center-position  \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\t2 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\t\t\t<\/h2>\n\t\t\t\t\t\t\t<h5 class=\"mkdf-st-subtitle\" >\n\t\t\t\t\u0e43\u0e15\u0e49\u0e15\u0e32\u0e04\u0e25\u0e49\u0e33 \u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-803deb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"803deb9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-959bc5a\" data-id=\"959bc5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c5e59c elementor-widget elementor-widget-text-editor\" data-id=\"4c5e59c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-kanit17\">\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38 <strong>&#8220;\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e44\u0e21\u0e48\u0e14\u0e35&#8221;<\/strong><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f0c5e0 elementor-widget elementor-widget-image\" data-id=\"1f0c5e0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"193\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/cause001.png\" class=\"attachment-large size-large wp-image-8038\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/cause001.png 600w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/cause001-300x97.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6855f03\" data-id=\"6855f03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cc73bc elementor-widget elementor-widget-text-editor\" data-id=\"9cc73bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-kanit17\">\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e34\u0e27 <strong>&#8220;\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e2d\u0e25\u0e25\u0e32\u0e40\u0e08\u0e19&#8221;<\/strong><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec9ecfd elementor-widget elementor-widget-image\" data-id=\"ec9ecfd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"193\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/cause002.png\" class=\"attachment-large size-large wp-image-8037\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/cause002.png 600w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/cause002-300x97.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d9dcca elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"3d9dcca\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85c8d15\" data-id=\"85c8d15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76f0c5 elementor-widget elementor-widget-mkdf_section_title\" data-id=\"b76f0c5\" data-element_type=\"widget\" data-widget_type=\"mkdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-section-title-holder  mkdf-st-top-tagline-position mkdf-st-center-position  \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t\t\t<span class=\"mkdf-st-tagline\" style=\"color: #1273B8\">\n\t\t\t\tEye Cream\t\t\t<\/span>\n\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\t15 \u0e27\u0e31\u0e19\u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e25\u0e08\u0e23\u0e34\u0e07\t\t\t<\/h2>\n\t\t\t\t\t\t\t<h5 class=\"mkdf-st-subtitle\" >\n\t\t\t\t\u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e08\u0e32\u0e01\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49b6cc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"49b6cc7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-058d4a6\" data-id=\"058d4a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ec0f85 elementor-widget elementor-widget-text-editor\" data-id=\"2ec0f85\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b><span style=\"font-size: x-large;\">\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32<\/span><br>\n<span style=\"color: #1273b8;\">\u0e25\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e19\u0e25\u0e07 \u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a\u0e02\u0e36\u0e49\u0e19<\/span>\n<\/b><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d1c2ce elementor-widget elementor-widget-image\" data-id=\"9d1c2ce\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"588\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/15-001.png\" class=\"attachment-large size-large wp-image-8051\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/15-001.png 685w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/15-001-300x258.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/15-001-600x515.png 600w\" sizes=\"(max-width: 685px) 100vw, 685px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47363c4 elementor-widget elementor-widget-text-editor\" data-id=\"47363c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-prompt-small-comment\">* \u0e1c\u0e25\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e43\u0e19\u0e2d\u0e32\u0e2a\u0e32\u0e2a\u0e21\u0e31\u0e04\u0e23 10 \u0e04\u0e19\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e04\u0e23\u0e35\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07 acetyl hexapeptide-8 500ppm (0.02%) \u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e04\u0e23\u0e35\u0e21\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e42\u0e14\u0e22\u0e17\u0e32\u0e27\u0e31\u0e19\u0e25\u0e30 2\u0e04\u0e23\u0e31\u0e49\u0e07\/\u0e27\u0e31\u0e19<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f6d473\" data-id=\"5f6d473\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1ea637 elementor-widget elementor-widget-text-editor\" data-id=\"e1ea637\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b><span style=\"font-size: x-large;\">\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e04\u0e25\u0e49\u0e33\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32<\/span><br>\n<span style=\"color: #1273b8;\">\u0e43\u0e15\u0e49\u0e15\u0e32\u0e14\u0e39\u0e01\u0e23\u0e30\u0e08\u0e48\u0e32\u0e07\u0e43\u0e2a<\/span>\n<\/b><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71fc6cd elementor-widget elementor-widget-image\" data-id=\"71fc6cd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"588\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/15-002.png\" class=\"attachment-large size-large wp-image-8050\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/15-002.png 685w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/15-002-300x258.png 300w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/15-002-600x515.png 600w\" sizes=\"(max-width: 685px) 100vw, 685px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75bb4b4 elementor-widget elementor-widget-text-editor\" data-id=\"75bb4b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"font-prompt-small-comment\">* \u0e08\u0e32\u0e01\u0e01\u0e23\u0e32\u0e1f \u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e04\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e35\u0e1c\u0e34\u0e27 (L) \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 1.03% \u0e43\u0e19 15 \u0e27\u0e31\u0e19 \u0e2a\u0e23\u0e38\u0e1b\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 \u0e1c\u0e34\u0e27\u0e43\u0e15\u0e49\u0e14\u0e27\u0e07\u0e15\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e23\u0e30\u0e08\u0e48\u0e32\u0e07\u0e43\u0e2a\u0e02\u0e36\u0e49\u0e19 1.03% \u0e43\u0e19 15 \u0e27\u0e31\u0e19 (\u0e42\u0e14\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49 L=0 \u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e2a\u0e35\u0e04\u0e25\u0e49\u0e33, L=100 \u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e02\u0e32\u0e27) \u0e04\u0e48\u0e32\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e2a\u0e35\u0e1c\u0e34\u0e27 (ITA) \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 2.97% \u0e43\u0e19 15 \u0e27\u0e31\u0e19 \u0e2a\u0e23\u0e38\u0e1b\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e2a\u0e35\u0e1c\u0e34\u0e27\u0e43\u0e15\u0e49\u0e14\u0e27\u0e07\u0e15\u0e32\u0e01\u0e23\u0e30\u0e08\u0e48\u0e32\u0e07\u0e43\u0e2a\u0e02\u0e36\u0e49\u0e19 2.97% \u0e43\u0e19 15 \u0e27\u0e31\u0e19<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18c6010 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"18c6010\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f914c43\" data-id=\"f914c43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5961d05 elementor-widget elementor-widget-mkdf_section_title\" data-id=\"5961d05\" data-element_type=\"widget\" data-widget_type=\"mkdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-section-title-holder  mkdf-st-top-tagline-position mkdf-st-center-position  \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t\t\t<span class=\"mkdf-st-tagline\" style=\"color: #1273B8\">\n\t\t\t\tReview\t\t\t<\/span>\n\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" style=\"color: #000000\">\n\t\t\t\t\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e08\u0e23\u0e34\u0e07\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44df7f2 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"44df7f2\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW010.png\" alt=\"2023REAW010\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW009.png\" alt=\"2023REAW009\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW008.png\" alt=\"2023REAW008\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW007.png\" alt=\"2023REAW007\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW006.png\" alt=\"2023REAW006\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW005.png\" alt=\"2023REAW005\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW004.png\" alt=\"2023REAW004\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW003.png\" alt=\"2023REAW003\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW002.png\" alt=\"2023REAW002\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW001.png\" alt=\"2023REAW001\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/2023REAW011.png\" alt=\"2023REAW011\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a25298a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"a25298a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb75388\" data-id=\"bb75388\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-61aaacf elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"61aaacf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b3b326d\" data-id=\"b3b326d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ac3d89 elementor-widget elementor-widget-mkdf_section_title\" data-id=\"9ac3d89\" data-element_type=\"widget\" data-widget_type=\"mkdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-section-title-holder  mkdf-st-top-tagline-position mkdf-st-center-position  \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t\t\t<span class=\"mkdf-st-tagline\" style=\"color: #1273B8\">\n\t\t\t\tEye Cream\t\t\t<\/span>\n\t\t\t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\t\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\t\t\t<\/h2>\n\t\t\t\t\t\t\t<h5 class=\"mkdf-st-subtitle\" >\n\t\t\t\t \t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5cfd42e elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-row-grid-no mkdf-disabled-bg-image-bellow-no\" data-id=\"5cfd42e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-de0c1e3\" data-id=\"de0c1e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9fb9b43\" data-id=\"9fb9b43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4378f6 elementor-widget elementor-widget-image\" data-id=\"f4378f6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1462\" src=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/products-png2.png\" class=\"attachment-full size-full wp-image-7778\" alt=\"\" srcset=\"https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/products-png2.png 1000w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/products-png2-205x300.png 205w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/products-png2-700x1024.png 700w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/products-png2-768x1123.png 768w, https:\/\/drjill.co.th\/home\/wp-content\/uploads\/2023\/04\/products-png2-600x877.png 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a210b99\" data-id=\"a210b99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78e50f8 elementor-widget elementor-widget-text-editor\" data-id=\"78e50f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e01\u0e23\u0e30\u0e08\u0e48\u0e32\u0e07\u0e43\u0e2a\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32 \u0e43\u0e2b\u0e49\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32\u0e25\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e19\u0e25\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e34\u0e27\u0e41\u0e25\u0e14\u0e39\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a \u0e2d\u0e48\u0e2d\u0e19\u0e40\u0e22\u0e32\u0e27\u0e19\u0e4c<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a305658 elementor-mobile-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a305658\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e25\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e19\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e25\u0e14\u0e23\u0e2d\u0e22\u0e04\u0e25\u0e49\u0e33\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2d\u0e48\u0e2d\u0e19\u0e42\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e1c\u0e34\u0e27\u0e23\u0e2d\u0e1a\u0e14\u0e27\u0e07\u0e15\u0e32<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e2a\u0e20\u0e32\u0e1e\u0e1c\u0e34\u0e27 \u0e41\u0e21\u0e49\u0e1c\u0e34\u0e27\u0e41\u0e1e\u0e49\u0e07\u0e48\u0e32\u0e22<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a026ca elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"8a026ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-450e08d elementor-widget elementor-widget-text-editor\" data-id=\"450e08d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-cart\" viewBox=\"0 0 16 16\">\n  <path d=\"M0 1.5A.5.5 0 0 1 .5 1H2a.5.5 0 0 1 .485.379L2.89 3H14.5a.5.5 0 0 1 .491.592l-1.5 8A.5.5 0 0 1 13 12H4a.5.5 0 0 1-.491-.408L2.01 3.607 1.61 2H.5a.5.5 0 0 1-.5-.5zM3.102 4l1.313 7h8.17l1.313-7H3.102zM5 12a2 2 0 1 0 0 4 2 2 0 0 0 0-4zm7 0a2 2 0 1 0 0 4 2 2 0 0 0 0-4zm-7 1a1 1 0 1 1 0 2 1 1 0 0 1 0-2zm7 0a1 1 0 1 1 0 2 1 1 0 0 1 0-2z\"\/>\n<\/svg>\n\n<i class=\"bi bi-cart\"><\/i> \u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-368807f\" data-id=\"368807f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>https:\/\/drjill.co.th\/home\/files-drjl\/vid [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"om_disable_all_campaigns":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-7708","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/drjill.co.th\/home\/wp-json\/wp\/v2\/pages\/7708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drjill.co.th\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drjill.co.th\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drjill.co.th\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drjill.co.th\/home\/wp-json\/wp\/v2\/comments?post=7708"}],"version-history":[{"count":373,"href":"https:\/\/drjill.co.th\/home\/wp-json\/wp\/v2\/pages\/7708\/revisions"}],"predecessor-version":[{"id":10571,"href":"https:\/\/drjill.co.th\/home\/wp-json\/wp\/v2\/pages\/7708\/revisions\/10571"}],"wp:attachment":[{"href":"https:\/\/drjill.co.th\/home\/wp-json\/wp\/v2\/media?parent=7708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}